{"id":8671,"date":"2021-02-15T07:49:08","date_gmt":"2021-02-15T12:49:08","guid":{"rendered":"https:\/\/cienciassociales.uniandes.edu.co\/ciencia-politica\/?post_type=boletin-depolitica&#038;p=8671"},"modified":"2021-02-15T08:01:48","modified_gmt":"2021-02-15T13:01:48","slug":"69","status":"publish","type":"boletin-depolitica","link":"https:\/\/cienciassociales.uniandes.edu.co\/ciencia-politica-estudios-globales\/boletin-depolitica\/69\/","title":{"rendered":"Bolet\u00edn 69"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"8671\" class=\"elementor elementor-8671\" data-elementor-post-type=\"boletin-depolitica\">\n\t\t\t\t\t\t<section class=\"has_ae_slider elementor-section elementor-top-section elementor-element elementor-element-07f43d6 elementor-section-boxed elementor-section-height-default elementor-section-height-default ae-bg-gallery-type-default\" data-id=\"07f43d6\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"has_ae_slider elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-72fa0d9 ae-bg-gallery-type-default\" data-id=\"72fa0d9\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5d7a905 elementor-widget elementor-widget-heading\" data-id=\"5d7a905\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\"><b>Editorial<\/b><\/h1>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-54aa98f elementor-widget elementor-widget-heading\" data-id=\"54aa98f\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">LAURA WILLS<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-109b557 elementor-widget elementor-widget-text-editor\" data-id=\"109b557\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p><a href=\"http:\/\/l.wills21@uniandes.edu.co\" target=\"_blank\" rel=\"noopener\">l.wills21@uniandes.edu.co<\/a><\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-25bc2d8 elementor-widget elementor-widget-text-editor\" data-id=\"25bc2d8\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p align=\"justify\"><span>El 27 de abril asist\u00ed a un seminario sobre democracia y partidos pol\u00edticos en Am\u00e9rica Latina que se llev\u00f3 a cabo en la Universidad Sergio Arboleda. Reconocidos acad\u00e9micos provenientes de diferentes pa\u00edses realizaron un balance sobre diversos temas relacionados con la materia, reflexionaron sobre las caracter\u00edsticas de la representaci\u00f3n pol\u00edtica y sobre los gobiernos de derecha presentes en algunos pocos pa\u00edses de la regi\u00f3n, sobre las estructuras organizativas formales e informales de los partidos pol\u00edticos y sobre las relaciones program\u00e1ticas, personalistas y clientelares que se establecen entre los pol\u00edticos y los votantes. Algunas ideas quedaron sobre la mesa y me parece que merecen ser discutidas y abordadas en nuestras agendas de investigaci\u00f3n. A continuaci\u00f3n resumo solo unas pocas.<\/span><br \/><br \/><span>En primer lugar, los conferencistas nos recordaron que la regi\u00f3n latinoamericana, y particularmente los pa\u00edses andinos, confrontan actualmente una crisis de representaci\u00f3n pol\u00edtica. En varios casos la crisis la explica el declive electoral que los partidos tradicionales han sufrido como consecuencia de las precarias respuestas que los mismos dieron a problem\u00e1ticas en los planes econ\u00f3mico y social.<\/span><br \/><br \/><span>En segundo lugar, han surgido l\u00edderes antipartidarios y populistas y han ocupado los espacios que los partidos tradicionales han perdido. En la mayor\u00eda de los casos estos l\u00edderes se olvidan de respaldar sus acciones en organizaciones partidarias formales y act\u00faan guiados por sus propias pasiones ignorando en repetidas oportunidades el engranaje institucional existente. Uno de los expositores llam\u00f3 la atenci\u00f3n sobre el caso venezolano al que se refiri\u00f3 no ya como una democracia representativa sino como una modalidad de autoritarismo.<\/span><br \/><br \/><span>En tercer lugar, varias veces se repiti\u00f3 la idea sobre la presencia cada vez menor de organizaciones partidarias con estructuras s\u00f3lidas y permanentes, con presencia nacional y con ra\u00edces fuertes en la sociedad. Lo que existe hoy m\u00e1s t\u00edpicamente son partidos electoralistas, con votantes y sellos muy vol\u00e1tiles y dirigidos por figuras carism\u00e1ticas. Los hay con esas caracter\u00edsticas en los diferentes puntos del espectro ideol\u00f3gico. Partidos tanto de izquierda como de derecha son hoy menos estructurados que antes. Adem\u00e1s, se subray\u00f3, los partidos ya no funcionan guiados por estatutos y reglas formales; predominan relaciones y pr\u00e1cticas informales. Finalmente, se resalt\u00f3 la preponderancia que tienen las pr\u00e1cticas clientelares y personalistas en los diferentes pa\u00edses de la regi\u00f3n. Las relaciones estrechas entre pol\u00edticos y votantes \u2014marcadas muchas veces por intercambios materiales que benefician a las dos partes, incluida la compra de votos\u2014 son las que orientan el accionar pol\u00edtico.<\/span><br \/><br \/><span>Para concluir, es importante que reconozcamos esta realidad latinoamericana. Los retos contempor\u00e1neos que se le presentan a los sistemas pol\u00edticos de la regi\u00f3n son innumerables, y nosotros los ciudadanos, hacemos parte de la ecuaci\u00f3n. Por lo mismo, deber\u00edamos reflexionar sobre nuestra porci\u00f3n de responsabilidad y sobre posibilidades de respuesta que estamos en capacidad de ofrecer.<\/span><br \/><br \/><strong>\u00bfComentarios?<\/strong><br \/><a href=\"mailto:l.wills21@uniandes.edu.co\">l.wills21@uniandes.edu.co<\/a><\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-878d1f2 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"878d1f2\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3a325f9 elementor-widget elementor-widget-heading\" data-id=\"3a325f9\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">LA FOTO<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"has_ae_slider elementor-section elementor-top-section elementor-element elementor-element-62e523c elementor-section-boxed elementor-section-height-default elementor-section-height-default ae-bg-gallery-type-default\" data-id=\"62e523c\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"has_ae_slider elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ec4bfba ae-bg-gallery-type-default\" data-id=\"ec4bfba\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-af2dd04 elementor-widget elementor-widget-heading\" data-id=\"af2dd04\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Los autores y su obra<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f0dc7a1 elementor-widget elementor-widget-image\" data-id=\"f0dc7a1\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"400\" height=\"533\" src=\"https:\/\/cienciassociales.uniandes.edu.co\/ciencia-politica-estudios-globales\/wp-content\/uploads\/sites\/11\/2021\/02\/69-a.jpg\" class=\"attachment-large size-large wp-image-8673\" alt=\"\" srcset=\"https:\/\/cienciassociales.uniandes.edu.co\/ciencia-politica-estudios-globales\/wp-content\/uploads\/sites\/11\/2021\/02\/69-a.jpg 400w, https:\/\/cienciassociales.uniandes.edu.co\/ciencia-politica-estudios-globales\/wp-content\/uploads\/sites\/11\/2021\/02\/69-a-225x300.jpg 225w\" sizes=\"(max-width: 400px) 100vw, 400px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b0bcb25 elementor-widget elementor-widget-text-editor\" data-id=\"b0bcb25\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p style=\"text-align: center;\"><span>Foto: Miguel Olaya<\/span><\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5115e3f elementor-widget elementor-widget-text-editor\" data-id=\"5115e3f\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p align=\"justify\"><span>El 28 de abril la Facultad de Econom\u00eda lanz\u00f3 el \u201clibro blanco\u201d\u00a0<\/span><em>Pol\u00edticas antidroga en Colombia<\/em><span>:\u00a0<\/span><em>\u00e9xitos<\/em><span>,\u00a0<\/span><em>fracasos y desaf\u00edos<\/em><span>, compilado por Alejandro Gaviria y Daniel Mej\u00eda. Algunos de los autores que contribuyeron a este libro est\u00e1n asociados con el Departamento de Ciencia Pol\u00edtica. De izquierda a derecha: Carolina Cepeda (autora, junto con Arlene Tickner, de \u201cLas drogas il\u00edcitas en la relaci\u00f3n Colombia-Estados Unidos: balance y perspectivas\u201d), Miguel Garc\u00eda (autor de \u201cCultivos il\u00edcitos, participaci\u00f3n pol\u00edtica y confianza institucional\u201d), Diego Garc\u00eda y Catalina Arreaza (autores, junto con Arlene Tickner, de \u201cActores violentos no estatales en Colombia\u201d).<\/span><\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"has_ae_slider elementor-section elementor-top-section elementor-element elementor-element-ff1cd6a elementor-section-boxed elementor-section-height-default elementor-section-height-default ae-bg-gallery-type-default\" data-id=\"ff1cd6a\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"has_ae_slider elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6e08983 ae-bg-gallery-type-default\" data-id=\"6e08983\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-579a317 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"579a317\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4d58979 elementor-widget elementor-widget-heading\" data-id=\"4d58979\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Noticias<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ea82fa6 elementor-widget elementor-widget-heading\" data-id=\"ea82fa6\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Sandra Borda en Catar<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-09ddede elementor-widget elementor-widget-text-editor\" data-id=\"09ddede\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p align=\"justify\"><span>Entre el 9 y el 10 de mayo, Sandra Borda asistir\u00e1 a la VI Conferencia Enriching the Middle East\u2019s Economic Future, que se celebrar\u00e1 en Doha, capital de Catar. Sandra asiste por invitaci\u00f3n del\u00a0<\/span><a href=\"http:\/\/www.international.ucla.edu\/cmed\/\" target=\"_blank\" rel=\"noopener\">Centro para el Desarrollo del Medio Oriente<\/a><span>\u00a0de UCLA y el Ministerio de Estado de Catar, organizadores de esta conferencia.<\/span><\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3075b86 elementor-widget elementor-widget-heading\" data-id=\"3075b86\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Novedades bibliogr\u00e1ficas<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0f0f752 elementor-widget elementor-widget-text-editor\" data-id=\"0f0f752\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p><span>Esta semana se lanz\u00f3 el libro\u00a0<\/span><em>Medios<\/em><span>,\u00a0<\/span><em>democracia y poder<\/em><span>, una compilaci\u00f3n realizada por Angelika Rettberg (Departamento de Ciencia Pol\u00edtica) y \u00d3mar Rinc\u00f3n (Centro de Estudios del Periodismo). Este libro, publicado con el auspicio de Plataforma Democr\u00e1tica, re\u00fane contribuciones de autores de Argentina, Ecuador, Venezuela y Colombia, algunas de las cuales fueron presentadas como ponencias en el\u00a0<\/span><a href=\"http:\/\/www.semana.com\/nacion\/foro-medios-democracia-poder-mirada-comparada-desde-colombia-ecuador-venezuela-argentina\/130907-3.aspx\" target=\"_blank\" rel=\"noopener\">foro del mismo nombre que realizaron el Departamento y el Ceper en noviembre de 2009<\/a><span>.<\/span><br \/><br \/><span>El 3 de mayo, en la Sala del Consejo de la Universidad de los Andes, ser\u00e1 el lanzamiento de\u00a0<\/span><em>La desmovilizaci\u00f3n de los paramilitares en Colombia<\/em><span>, compilado por Elvira Mar\u00eda Restrepo y Bruce Bagley. un par de rese\u00f1as sobre el libro puede encontrarse en la secci\u00f3n Opini\u00f3n y an\u00e1lisis. Antes del lanzamiento, a las 2 de la tarde, se llevar\u00e1 a cabo un conversatorio: \u201c\u00bfHacia d\u00f3nde va el conflicto armado colombiano?\u201d. Consulte la secci\u00f3n Agenda para m\u00e1s informaci\u00f3n.<\/span><\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bb686f0 elementor-widget elementor-widget-heading\" data-id=\"bb686f0\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Nuevo sitio de ConPaz<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-97f0104 elementor-widget elementor-widget-text-editor\" data-id=\"97f0104\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p><span>El Programa de Investigaci\u00f3n sobre Conflicto Armado y Construcci\u00f3n de Paz (ConPaz) presenta la pr\u00f3xima semana\u00a0<\/span><a href=\"http:\/\/conpaz.uniandes.edu.co\/\" target=\"_blank\" rel=\"noopener\">su nuevo sitio web<\/a><span>. El sitio recoge informaci\u00f3n sobre las publicaciones y cursos que, desde 2003, han producido investigadores asociados al programa, as\u00ed como los trabajos de grado y tesis de estudiantes que han estado relacionados con sus l\u00edneas de investigaci\u00f3n como justicia transicional, econom\u00eda pol\u00edtica del conflicto, negociaciones de paz y sector privado y construcci\u00f3n de paz. La mayor\u00eda de estos contenidos puede consultarse en l\u00ednea. ConPaz naci\u00f3 en 2003 como pionero en la investigaci\u00f3n sobre construcci\u00f3n de paz y este sitio busca ser una referencia para los interesados en estos temas.<\/span><\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1108596 elementor-widget elementor-widget-heading\" data-id=\"1108596\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Escuela de verano con Gustavo Duncan<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-33cf618 elementor-widget elementor-widget-text-editor\" data-id=\"33cf618\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p><span>\u201c<\/span><a href=\"https:\/\/appsciso.uniandes.edu.co\/docs\/descargar.php?f=.\/data\/Cp_2011.pdf\" target=\"_blank\" rel=\"noopener\">Crimen, sociedad y estado contempor\u00e1neo<\/a><span>\u201d ser\u00e1 el curso que el Departamento de Ciencia Pol\u00edtica ofrecer\u00e1 para la escuela de verano del periodo intersemestral de este a\u00f1o, del 14 de junio al 7 de julio. El curso ser\u00e1 dictado por\u00a0<\/span><a href=\"https:\/\/appsciso.uniandes.edu.co\/cv.php\/99\/index.php\" target=\"_blank\" rel=\"noopener\">Gustavo Duncan<\/a><span>, que vendr\u00e1 desde Illinois, donde adelanta sus estudios doctorales en la Universidad del Noroeste. Quienes est\u00e9n interesados en el curso pueden inscribirse entre el 30 y el 31 de mayo en la Coordinaci\u00f3n de Posgrados del Departamento.<\/span><\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-984f525 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"984f525\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"has_ae_slider elementor-section elementor-top-section elementor-element elementor-element-72fbf34 elementor-section-boxed elementor-section-height-default elementor-section-height-default ae-bg-gallery-type-default\" data-id=\"72fbf34\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"has_ae_slider elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-38aacfe ae-bg-gallery-type-default\" data-id=\"38aacfe\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6bafb75 elementor-widget elementor-widget-heading\" data-id=\"6bafb75\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Opini\u00f3n y An\u00e1lisis<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"has_ae_slider elementor-section elementor-top-section elementor-element elementor-element-9f0836e elementor-section-boxed elementor-section-height-default elementor-section-height-default ae-bg-gallery-type-default\" data-id=\"9f0836e\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"has_ae_slider elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ed5f726 ae-bg-gallery-type-default\" data-id=\"ed5f726\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b6eb16d elementor-widget elementor-widget-heading\" data-id=\"b6eb16d\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Comentarios sobre La desmovilizaci\u00f3n de los paramilitares en Colombia<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d2e03cc elementor-widget elementor-widget-text-editor\" data-id=\"d2e03cc\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p align=\"justify\"><span>Por MANUEL JOS\u00c9 CEPEDA ESPINOSA<\/span><b><br \/><\/b><span>M\u00e1s all\u00e1 de ser un referente obligado para cualquiera que aspire a entender los procesos de desarme, desmovilizaci\u00f3n y reintegraci\u00f3n en los \u00e1mbitos nacional, territorial y local, este libro es una mirada novedosa a una caracter\u00edstica poco explorada de Colombia: la expansi\u00f3n de las fronteras del estado de derecho en el territorio dominado por el imperio de la fuerza. \u00bfC\u00f3mo enmarcar dentro de una ley la desmovilizaci\u00f3n m\u00e1s grande en la historia de Colombia de actores armados no derrotados? \u00bfPor qu\u00e9 aceptaron desmovilizarse sin que hubiera amnist\u00eda o indulto tambi\u00e9n por primera vez en nuestra historia? \u00bfQu\u00e9 permiti\u00f3 no solo visibilizar a las v\u00edctimas de las atrocidades de los paramilitares sino empoderarlas hasta niveles insospechados, as\u00ed sus expectativas sean a\u00fan mayores? \u00bfCu\u00e1les han sido los logros y fallas de un proceso de justicia transicional, de por s\u00ed especial, transformado por la intervenci\u00f3n de la Corte Constitucional, reconfigurado por el papel activo de las v\u00edctimas y reorientado por el Ejecutivo con la extradici\u00f3n de los jefes paramilitares a los Estados Unidos? A estas y otras preguntas, el lector encontrar\u00e1 diversas respuestas expuestas con rigor por un grupo selecto de expertos que deshilvanan la complejidad colombiana y nos invitan a desprendernos de las ideas recibidas. Al final, rebasando el caso colombiano, ver\u00e1 con m\u00e1s claridad las encrucijadas derivadas de las tensiones entre paz y justicia, le dar\u00e1 m\u00e1s valor a resultados positivos injustamente minimizados y tendr\u00e1 mejores elementos de juicio para ponderar las potencialidades y limitaciones de las reglas jur\u00eddicas para ofrecer soluciones a problemas socio-pol\u00edticos.<\/span><b><br \/><\/b><span>* Manuel Jos\u00e9 Cepeda Espinosa fue magistrado de la Corte Constitucional de Colombia.<\/span><b><br \/><br \/><\/b><span>Por CHRISTINE BELL<\/span><b><br \/><\/b><span>La manera como se resuelve el legado de un conflicto constituye el eje central de los dilemas morales, pol\u00edticos y legales que se dan en pa\u00edses que buscan superar conflictos arraigados a trav\u00e9s de procesos de justicia transicional. El debate sobre la Ley de Justicia y Paz en Colombia va en esta direcci\u00f3n. El caso de Colombia, sin embargo, desaf\u00eda todos los supuestos de la justicia transicional: no es claro si hay una salida del conflicto, si se est\u00e1 ante un verdadero proceso de paz o tampoco si la &#8216;justicia&#8217; es la meta de los postulados de justicia transicional que informan el proceso con los paramilitares. M\u00e1s a\u00fan, se podr\u00eda decir que Colombia es un caso donde el discurso de la justicia transicional se vuelve un verdadero campo de batalla y con ello se revela el \u201clado oscuro\u201d de este concepto. Nadie puede ignorar la importancia de este libro o la de Colombia. Con ensayos de acad\u00e9micos, periodistas y analistas prominentes este libro cubre casi todos los aspectos de la Ley de Justicia y Paz y de su lugar en la literatura sobre justicia transicional. Adem\u00e1s contiene una gran cantidad de informaci\u00f3n que lo pone a la vanguardia de los an\u00e1lisis existentes.<\/span><b><br \/><\/b><span>* Christine Bell es catedr\u00e1tica de Derecho Internacional P\u00fablico en la Universidad de Ulster.<\/span><\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8ccab95 elementor-widget elementor-widget-heading\" data-id=\"8ccab95\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Academia y pol\u00edtica<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1142555 elementor-widget elementor-widget-text-editor\" data-id=\"1142555\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p><span>Por ARLENE B. TICKNER en\u00a0<\/span><a href=\"http:\/\/www.elespectador.com\/opinion\/columna-265455-academia-y-politica\" target=\"_blank\" rel=\"noopener\">El Espectador<\/a><b><br \/><\/b><span>Entre las pel\u00edculas que vi en Semana Santa, la merecida ganadora del Oscar,\u00a0<\/span><em>Trabajo confidencial<\/em><span>\u00a0fue la m\u00e1s impactante. Adem\u00e1s de detallar magistralmente los or\u00edgenes y desenlace de la crisis financiera mundial el documental nos acerca a algunos de sus principales responsables. No se trata de una historia del todo desconocida en Am\u00e9rica Latina.<\/span><\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c4f21ab elementor-widget elementor-widget-heading\" data-id=\"c4f21ab\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Pol\u00edtica exterior en la sombra<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3f280dd elementor-widget elementor-widget-text-editor\" data-id=\"3f280dd\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p><span>Por ARLENE B. TICKNER en\u00a0<\/span><a href=\"http:\/\/www.elespectador.com\/impreso\/opinion\/columna-264255-politica-exterior-sombra\" target=\"_blank\" rel=\"noopener\">El Espectador<\/a><b><br \/><\/b><span>En el contexto pol\u00edtico colombiano \u00c1lvaro Uribe se ha convertido en el \u201cback seat driver\u201d m\u00e1s irritante de todos. Hasta ahora, Juan Manuel Santos ha administrado las constantes intromisiones de su antecesor con la necesaria dosis de paciencia y humor que tales comportamientos exigen. Sin embargo, las opiniones de Uribe est\u00e1n llegando a un punto en el que no s\u00f3lo pueden impacientar al conductor actual de Colombia sino que corren el riesgo de generar choques costosos.<\/span><\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f5d4233 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"f5d4233\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"has_ae_slider elementor-section elementor-top-section elementor-element elementor-element-a0528f1 elementor-section-boxed elementor-section-height-default elementor-section-height-default ae-bg-gallery-type-default\" data-id=\"a0528f1\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"has_ae_slider elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-a3cf909 ae-bg-gallery-type-default\" data-id=\"a3cf909\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a87f587 elementor-widget elementor-widget-heading\" data-id=\"a87f587\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Agenda<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d50da62 elementor-widget elementor-widget-heading\" data-id=\"d50da62\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Conversatorio \u00ab\u00bfHac\u00eda d\u00f3nde va el conflicto armado colombiano?\u00bb<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-09d412e elementor-widget elementor-widget-text-editor\" data-id=\"09d412e\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p><strong>Organiza:<\/strong><span>\u00a0Programa de Investigaci\u00f3n sobre Conflicto Armado y Construcci\u00f3n de Paz (ConPaz) del Departamento de Ciencia Pol\u00edtica de la Universidad de los Andes.<\/span><br \/><strong>Fecha:<\/strong><span>\u00a03 de mayo.<\/span><br \/><strong>Hora:<\/strong><span>\u00a02 p. m.<\/span><br \/><strong>Lugar:<\/strong><span>\u00a0Auditorio Alberto Lleras Camargo, Universidad de los Andes, calle 19A 1-37 este, Bogot\u00e1.<\/span><\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5cb81d0 elementor-widget elementor-widget-heading\" data-id=\"5cb81d0\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Lanzamiento del libro La desmovilizaci\u00f3n de los paramilitares en Colombia<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fb50a15 elementor-widget elementor-widget-text-editor\" data-id=\"fb50a15\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p><strong>Organiza:<\/strong><span>\u00a0Programa de Investigaci\u00f3n sobre Conflicto Armado y Construcci\u00f3n de Paz (ConPaz) del Departamento de Ciencia Pol\u00edtica de la Universidad de los Andes.<\/span><br \/><strong>Fecha:<\/strong><span>\u00a03 de mayo.<\/span><br \/><strong>Hora:<\/strong><span>\u00a05:30 p. m.<\/span><br \/><strong>Lugar:<\/strong><span>\u00a0Sala del Consejo, Edificio Pedro Navas, Universidad de los Andes, carrera 1 18A-12, Bogot\u00e1.<\/span><\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-66a6dd8 elementor-widget elementor-widget-heading\" data-id=\"66a6dd8\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Conferencia \u00abReflexiones sobre el estado y el futuro de la pol\u00edtica comparada\u00bb con Richard Snyder (Universidad Brown)<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d16ad09 elementor-widget elementor-widget-text-editor\" data-id=\"d16ad09\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p align=\"justify\"><strong>Organiza:<\/strong><span>\u00a0Departamento de Ciencia Pol\u00edtica de la Universidad de los Andes.<\/span><br \/><strong>Fecha:<\/strong><span>\u00a011 de mayo.<\/span><br \/><strong>Hora:<\/strong><span>\u00a010 a. m.<\/span><br \/><strong>Lugar:<\/strong><span>\u00a0Auditorio Mario Laserna C, Universidad de los Andes, carrera 1 este 19A-40, Bogot\u00e1.<\/span><\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-856b10b elementor-widget elementor-widget-heading\" data-id=\"856b10b\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Lanzamiento del libro Colombia y el mundo, 2010: opini\u00f3n p\u00fablica y pol\u00edtica internacional<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6e95540 elementor-widget elementor-widget-text-editor\" data-id=\"6e95540\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p><strong>Organiza:<\/strong><span>\u00a0Centro de Estudios Internacionales del Departamento de Ciencia Pol\u00edtica y Escuela de Gobierno Alberto Lleras Camargo de la Universidad de los Andes.<\/span><br \/><strong>Fecha:<\/strong><span>\u00a012 de mayo.<\/span><br \/><strong>Hora:<\/strong><span>\u00a0por confirmar<\/span><br \/><strong>Lugar:<\/strong><span>\u00a0por confirmar.<\/span><\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f52acaf elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"f52acaf\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"has_ae_slider elementor-section elementor-top-section elementor-element elementor-element-986d1f1 elementor-section-boxed elementor-section-height-default elementor-section-height-default ae-bg-gallery-type-default\" data-id=\"986d1f1\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"has_ae_slider elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-f370d98 ae-bg-gallery-type-default\" data-id=\"f370d98\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c022d9b elementor-widget elementor-widget-heading\" data-id=\"c022d9b\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Oportunidades<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8461095 elementor-widget elementor-widget-text-editor\" data-id=\"8461095\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p><b><a href=\"http:\/\/www.koica.go.kr\/english\/schemes\/training\/index.html\" target=\"_blank\" rel=\"noopener\">Agencia Coreana de Cooperaci\u00f3n Internacional +<\/a><br \/><\/b><span>Programas de posgrado en diferente \u00e1reas en la Rep\u00fablica de Corea.<\/span><b><br \/><br \/><a href=\"http:\/\/www.aiesec.org\/colombia\/andes\" target=\"_blank\" rel=\"noopener\">AIESEC +<\/a><br \/><\/b><span>Oportunidades de intercambio y pasant\u00edas.<\/span><b><br \/><br \/><a href=\"http:\/\/www.balsillieschool.ca\/imagining-global-governance\" target=\"_blank\" rel=\"noopener\">Balsillie School +<\/a><br \/><\/b><span>Conferencia Imagining Global Governance: Change and Continuity. Se llevar\u00e1 a cabo en Waterloo, Canad\u00e1 en octubre.<\/span><b><br \/><br \/><a href=\"http:\/\/web.worldbank.org\/WBSITE\/EXTERNAL\/EXTHRJOBS\/0,,contentMDK:20515930~menuPK:64262360~pagePK:64262408~piPK:64262191~theSitePK:1058433,00.html\" target=\"_blank\" rel=\"noopener\">Banco Mundial +<\/a><br \/><\/b><span>Convocatoria permanente para asociaci\u00f3n de profesionales j\u00f3venes.<\/span><b><br \/><br \/><a href=\"http:\/\/www.berlinsummerschool.de\/welcome-to-the-berlin-summer-school-in-social-sciences\/\" target=\"_blank\" rel=\"noopener\">Berlin Summer School +<\/a><br \/><\/b><span>Curso de verano en Ciencias Sociales para estudiantes de doctorado que se realizar\u00e1 en Berl\u00edn entre el 17 y el 29 de julio. Inscirpciones hasta el 15 de mayo.<\/span><b><br \/><br \/><a href=\"https:\/\/ctp.uniandes.edu.co\/\" target=\"_blank\" rel=\"noopener\">Centro de trayectoria profesional de la Universidad de los Andes +<\/a><br \/><\/b><span>Ofertas laborales, charlas y talleres de orientaci\u00f3n profesional y presentaci\u00f3n de entrevistas.<\/span><b><br \/><br \/><a href=\"http:\/\/www.formacion.clacso.edu.ar\/\" target=\"_blank\" rel=\"noopener\">Clacso +<\/a><br \/><\/b><span>Diferentes programas de formaci\u00f3n a distancia.<\/span><b><br \/><br \/><a href=\"http:\/\/www.colciencias.gov.co\/convocatorias\" target=\"_blank\" rel=\"noopener\">Colciencias +<\/a><br \/><\/b><span>Convocatorias para becas para estudios de posgrado, entre otras.<\/span><b><br \/><br \/><a href=\"http:\/\/www.clacso.org.ar\/area_academica\/2b1.php\" target=\"_blank\" rel=\"noopener\">Consejo Latinoamericano de Ciencias Sociales +<\/a><br \/><\/b><span>Convocatoria para el premio Pedro Krotsch. El tema es pol\u00edticas y perspectivas sobre la evaluaci\u00f3n universitaria en Am\u00e9rica Latina y el Caribe. La inscripci\u00f3n se cierra el 30 de junio.<\/span><b><br \/><br \/><a href=\"http:\/\/www.nrc.org.co\/Convocatorias\/\" target=\"_blank\" rel=\"noopener\">Consejo Noruego para los Refugiados +<\/a><br \/><\/b><span>Convocatoria para diferentes cargos.<\/span><b><br \/><br \/><a href=\"http:\/\/www.emprenderpaz.org\/bases-de-la-convocatoria.html\" target=\"_blank\" rel=\"noopener\">Emprender Paz +<\/a><br \/><\/b><span>Cuarta versi\u00f3n del Premio Emprender Paz. Abierta a empresas privadas, fundaciones empresariales y gremios hasta el 31 de mayo.<\/span><b><br \/><br \/><a href=\"http:\/\/www.fundacionmbotin.org\/becas\/convocatorias.html\" target=\"_blank\" rel=\"noopener\">Fundaci\u00f3n Marcelino Bot\u00edn +<\/a><br \/><\/b><span>Convocatorias para becas en las Universidades Brown y Wellesley, as\u00ed como para apoyo a las artes.<\/span><b><br \/><br \/><a href=\"http:\/\/www.galilcol.ac.il\/page.asp?id=17\" target=\"_blank\" rel=\"noopener\">Galilee College +<\/a><br \/><\/b><span>Curso de verano \u201cCiencia Pol\u00edtica y estudios del Medio Oriente\u201d. Se llevar\u00e1 a cabo en julio.<\/span><b><br \/><br \/><a href=\"https:\/\/jobs.un.org\/Galaxy\/Release3\/vacancy\/vacancy.aspx?lang=1200http:\/\/www.nacionesunidas.org.co\/index.shtml?apc=vv---64129-64129&amp;s=v\" target=\"_blank\" rel=\"noopener\">Organizaci\u00f3n de las Naciones Unidas en Colombia +<\/a><br \/><\/b><span>Convocatoria para diferentes cargos en diferentes organizaciones y comisiones de la ONU.<\/span><b><br \/><br \/><a href=\"http:\/\/www.educoas.org\/Portal\/?culture=es\" target=\"_blank\" rel=\"noopener\">Organizaci\u00f3n de los Estados Americanos +<\/a><br \/><\/b><span>Oferta de becas y cursos de diferentes tipos, as\u00ed como oportunidades de financiaci\u00f3n de estudios.<\/span><b><br \/><br \/>Pontificia Universidad Javeriana \u2013 Facultad de Ciencia Pol\u00edtica y Relaciones Internacionales<br \/><\/b><span>Curso \u201cAn Introduction to experimental Political Science Research\u201d, a cargo de Rebecca B. Morton. Se dictar\u00e1 entre el 21 y el 23 de junio. Las inscripciones, abiertas hasta el 13 de mayo, se realizan escribieno un correo a\u00a0<\/span><a href=\"mailto:leonor.clavijo@javeriana.edu.co\">leonor.clavijo@javeriana.edu.co<\/a><span>. Para m\u00e1s informaci\u00f3n debe escribirse a\u00a0<\/span><a href=\"mailto:a.casas@javeriana.edu.co\">a.casas@javeriana.edu.co<\/a><b>.<br \/><br \/><a href=\"http:\/\/www.pnud.org.co\/sitio.shtml?apc=&amp;s=c&amp;cmd%5b313%5d=c-1-%27Oportunidades%20Laborales%27&amp;als%5bMIGA____%5d=Oportunidades%20Laborales\" target=\"_blank\" rel=\"noopener\">Programa de las Naciones Unidas para el Desarrollo +<\/a><br \/><\/b><span>Convocatorias para diferentes cargos.<\/span><b><br \/><br \/><\/b><a href=\"http:\/\/www.ucl.ac.uk\/ippr\/\" target=\"_blank\" rel=\"noopener\"><b>Red Colombiana de Relaciones Internacionales +<\/b><\/a><b><br \/><\/b><span>Abiertas las inscripciones para asistir al II Congreso, que se celebrar\u00e1 en septiembre en la Universidad de los Andes. Pueden presentarse ponencias hasta el 15 de junio. Los asistentes pueden inscribirse hasta el 1 de julio.<\/span><b><br \/><br \/><\/b><a href=\"http:\/\/hermesoft.esap.edu.co\/esap\/hermesoft\/portal\/home_1\/htm\/cont0.jsp?rec=not_4284.jsp\" target=\"_blank\" rel=\"noopener\"><b>Revista Nova et Vetera \u2013 ESAP +<\/b><\/a><b><br \/><\/b><span>Convocatoria para manuscritos para un n\u00famero especial sobre migraci\u00f3n y trata de personas. Se reciben manuiscritos hasta el 21 de junio en los correos\u00a0<\/span><a href=\"mailto:nova.vetera@esap.gov.co\">nova.vetera@esap.gov.co<\/a><span>\u00a0y\u00a0<\/span><a href=\"mailto:revistas.esap@gmail.com\">revistas.esap@gmail.com<\/a><span>.<\/span><b><br \/><br \/><\/b><a href=\"http:\/\/www.daad.co\/es\/13691\/index.html\" target=\"_blank\" rel=\"noopener\"><b>Servicio Alem\u00e1n de Intercambio Acad\u00e9mico +<\/b><\/a><b><br \/><\/b><span>Convocatoria para becas de investigaci\u00f3n para doctorandos y j\u00f3venes cient\u00edficos y estad\u00edas de investigaci\u00f3n. Se aceptan solicitudes hasta el 15 de septiembre. Tambi\u00e9n pueden encontrarse otras becas del DAAd\u00a0<\/span><a href=\"http:\/\/www.daad.co\/es\/12365\/index.html\" target=\"_blank\" rel=\"noopener\">aqu\u00ed<\/a><span>.<\/span><b><br \/><br \/><a href=\"http:\/\/registroacademico.unisabana.edu.co:8080\/econtinua\/detalle_curso.html?instanciaId=2004&amp;facultadId=14\" target=\"_blank\" rel=\"noopener\">Universidad de la Sabana +<\/a><br \/><\/b><span>Diplomado en Historia Contempor\u00e1nea. Las inscripciones se cierran el 4 de mayo.<\/span><b><br \/><br \/><a href=\"http:\/\/ica2012.univie.ac.at\/home\/\" target=\"_blank\" rel=\"noopener\">Universidad de Viena \u2013 Instituto Austriaco de Estudios de Am\u00e9rica Latina \u2013 Congreso Internacional de Americanistas +<\/a><br \/><\/b><span>Convocatoria para ponencias para el LIV Congreso Internacional de Americanistas, que se celebrar\u00e1 en Viena, Austria. Abierta del 15 de abril al 31 de agosto.<\/span><b><br \/><br \/><a href=\"http:\/\/www.modelonacionesunidasur.com\/\" target=\"_blank\" rel=\"noopener\">Universidad del Rosario +<\/a><br \/><\/b><span>Inscripciones para los modelos de las Naciones Unidas de la Universidad del Rosario que se celebrar\u00e1n en abril y en mayo.<\/span><b><br \/><br \/><a href=\"http:\/\/www.usergioarboleda.edu.co\/cerie\/encuentro-estudios-coreanos.htm\" target=\"_blank\" rel=\"noopener\">Universidad Sergio Arboleda +<\/a><br \/><\/b><span>Convocatoria para presentar ponencias para el V Encuentro de Estudios Coreanos en Am\u00e9rica Latina que se realizar\u00e1 en octubre. Abierta hasta el 15 de mayo.<\/span><b><br \/><br \/><a href=\"http:\/\/www.worldlearning.org\/268.htm\" target=\"_blank\" rel=\"noopener\">World Learning +<\/a><br \/><\/b><span>Vacantes para diferentes cargos.<\/span><\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a425349 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"a425349\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"has_ae_slider elementor-section elementor-top-section elementor-element elementor-element-0372771 elementor-section-boxed elementor-section-height-default elementor-section-height-default ae-bg-gallery-type-default\" data-id=\"0372771\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"has_ae_slider elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-b426d9a ae-bg-gallery-type-default\" data-id=\"b426d9a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8953827 elementor-widget elementor-widget-text-editor\" data-id=\"8953827\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p><strong>Directora<\/strong><br \/><span>Angelika Rettberg<\/span><br \/><strong>Editor<\/strong><br \/>Camilo Vargas<br \/><strong>Asistente<\/strong><br \/>Ana Gabriela Santamaria<br \/><strong>Desarrollo Web y Montaje<\/strong><br \/><span>Lesly Garz\u00f3n<\/span><br \/><strong>Dise\u00f1o Gr\u00e1fico<\/strong><br \/>V\u00edctor G\u00f3mez<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Editorial LAURA WILLS l.wills21@uniandes.edu.co El 27 de abril asist\u00ed a un seminario sobre democracia y partidos pol\u00edticos en Am\u00e9rica Latina&#8230;<\/p>\n","protected":false},"featured_media":0,"template":"","meta":{"_acf_changed":false},"tematica":[],"publico-objetivo":[],"class_list":["post-8671","boletin-depolitica","type-boletin-depolitica","status-publish","hentry"],"acf":[],"otros_campos":{"numero_ed_boletin":"69","fecha_pub_boletin":"20110429","cabezote_boletin":false,"boletines_profesores":""},"_links":{"self":[{"href":"https:\/\/cienciassociales.uniandes.edu.co\/ciencia-politica-estudios-globales\/wp-json\/wp\/v2\/boletin-depolitica\/8671","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cienciassociales.uniandes.edu.co\/ciencia-politica-estudios-globales\/wp-json\/wp\/v2\/boletin-depolitica"}],"about":[{"href":"https:\/\/cienciassociales.uniandes.edu.co\/ciencia-politica-estudios-globales\/wp-json\/wp\/v2\/types\/boletin-depolitica"}],"version-history":[{"count":0,"href":"https:\/\/cienciassociales.uniandes.edu.co\/ciencia-politica-estudios-globales\/wp-json\/wp\/v2\/boletin-depolitica\/8671\/revisions"}],"wp:attachment":[{"href":"https:\/\/cienciassociales.uniandes.edu.co\/ciencia-politica-estudios-globales\/wp-json\/wp\/v2\/media?parent=8671"}],"wp:term":[{"taxonomy":"tematica","embeddable":true,"href":"https:\/\/cienciassociales.uniandes.edu.co\/ciencia-politica-estudios-globales\/wp-json\/wp\/v2\/tematica?post=8671"},{"taxonomy":"publico-objetivo","embeddable":true,"href":"https:\/\/cienciassociales.uniandes.edu.co\/ciencia-politica-estudios-globales\/wp-json\/wp\/v2\/publico-objetivo?post=8671"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}